{"id":297,"count":5,"description":"","link":"https:\/\/osannavisconti.com\/it\/collezioni\/paglia-di-vienna\/","name":"Paglia di Vienna","slug":"paglia-di-vienna","taxonomy":"product_collection","parent":0,"meta":[],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Paglia di Vienna Collection - Osanna Visconti di Modrone<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/osannavisconti.com\/it\/collezioni\/paglia-di-vienna\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Paglia di Vienna Collection - Osanna Visconti di Modrone\" \/>\n<meta property=\"og:url\" content=\"https:\/\/osannavisconti.com\/it\/collezioni\/paglia-di-vienna\/\" \/>\n<meta property=\"og:site_name\" content=\"Osanna Visconti di Modrone\" \/>\n<meta property=\"og:image\" content=\"https:\/\/osannavisconti.com\/wp-content\/uploads\/2023\/09\/osanna-visconti-logo-black-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2048\" \/>\n\t<meta property=\"og:image:height\" content=\"1042\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/osannavisconti.com\\\/it\\\/collezioni\\\/paglia-di-vienna\\\/\",\"url\":\"https:\\\/\\\/osannavisconti.com\\\/it\\\/collezioni\\\/paglia-di-vienna\\\/\",\"name\":\"Paglia di Vienna Collection - Osanna Visconti di Modrone\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/osannavisconti.com\\\/it\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/osannavisconti.com\\\/it\\\/collezioni\\\/paglia-di-vienna\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/osannavisconti.com\\\/it\\\/collezioni\\\/paglia-di-vienna\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/osannavisconti.com\\\/it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Paglia di Vienna\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/osannavisconti.com\\\/it\\\/#website\",\"url\":\"https:\\\/\\\/osannavisconti.com\\\/it\\\/\",\"name\":\"Osanna Visconti - Bronze furnishings and design objects\",\"description\":\"Interior Design Milano\",\"publisher\":{\"@id\":\"https:\\\/\\\/osannavisconti.com\\\/it\\\/#organization\"},\"alternateName\":\"OVM\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/osannavisconti.com\\\/it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/osannavisconti.com\\\/it\\\/#organization\",\"name\":\"O.M. Visconti S.r.l.\",\"alternateName\":\"OMV\",\"url\":\"https:\\\/\\\/osannavisconti.com\\\/it\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/osannavisconti.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/osannavisconti.com\\\/wp-content\\\/uploads\\\/2025\\\/03\\\/osanna-visconti-logo-firma.png\",\"contentUrl\":\"https:\\\/\\\/osannavisconti.com\\\/wp-content\\\/uploads\\\/2025\\\/03\\\/osanna-visconti-logo-firma.png\",\"width\":1599,\"height\":810,\"caption\":\"O.M. Visconti S.r.l.\"},\"image\":{\"@id\":\"https:\\\/\\\/osannavisconti.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/facebook.com\\\/osannavisconti\",\"https:\\\/\\\/instagram.com\\\/osannavisconti\",\"https:\\\/\\\/linkedin.com\\\/showcase\\\/osannavisconti\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Paglia di Vienna Collection - Osanna Visconti di Modrone","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/osannavisconti.com\/it\/collezioni\/paglia-di-vienna\/","og_locale":"it_IT","og_type":"article","og_title":"Paglia di Vienna Collection - Osanna Visconti di Modrone","og_url":"https:\/\/osannavisconti.com\/it\/collezioni\/paglia-di-vienna\/","og_site_name":"Osanna Visconti di Modrone","og_image":[{"width":2048,"height":1042,"url":"https:\/\/osannavisconti.com\/wp-content\/uploads\/2023\/09\/osanna-visconti-logo-black-scaled.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/osannavisconti.com\/it\/collezioni\/paglia-di-vienna\/","url":"https:\/\/osannavisconti.com\/it\/collezioni\/paglia-di-vienna\/","name":"Paglia di Vienna Collection - Osanna Visconti di Modrone","isPartOf":{"@id":"https:\/\/osannavisconti.com\/it\/#website"},"breadcrumb":{"@id":"https:\/\/osannavisconti.com\/it\/collezioni\/paglia-di-vienna\/#breadcrumb"},"inLanguage":"it-IT"},{"@type":"BreadcrumbList","@id":"https:\/\/osannavisconti.com\/it\/collezioni\/paglia-di-vienna\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/osannavisconti.com\/it\/"},{"@type":"ListItem","position":2,"name":"Paglia di Vienna"}]},{"@type":"WebSite","@id":"https:\/\/osannavisconti.com\/it\/#website","url":"https:\/\/osannavisconti.com\/it\/","name":"Osanna Visconti - Bronze furnishings and design objects","description":"Interior Design Milano","publisher":{"@id":"https:\/\/osannavisconti.com\/it\/#organization"},"alternateName":"OVM","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/osannavisconti.com\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/osannavisconti.com\/it\/#organization","name":"O.M. Visconti S.r.l.","alternateName":"OMV","url":"https:\/\/osannavisconti.com\/it\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/osannavisconti.com\/it\/#\/schema\/logo\/image\/","url":"https:\/\/osannavisconti.com\/wp-content\/uploads\/2025\/03\/osanna-visconti-logo-firma.png","contentUrl":"https:\/\/osannavisconti.com\/wp-content\/uploads\/2025\/03\/osanna-visconti-logo-firma.png","width":1599,"height":810,"caption":"O.M. Visconti S.r.l."},"image":{"@id":"https:\/\/osannavisconti.com\/it\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/facebook.com\/osannavisconti","https:\/\/instagram.com\/osannavisconti","https:\/\/linkedin.com\/showcase\/osannavisconti"]}]}},"_links":{"self":[{"href":"https:\/\/osannavisconti.com\/it\/wp-json\/wp\/v2\/product_collection\/297","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/osannavisconti.com\/it\/wp-json\/wp\/v2\/product_collection"}],"about":[{"href":"https:\/\/osannavisconti.com\/it\/wp-json\/wp\/v2\/taxonomies\/product_collection"}],"wp:post_type":[{"href":"https:\/\/osannavisconti.com\/it\/wp-json\/wp\/v2\/product?product_collection=297"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}